{"id":5052,"date":"2024-11-13T14:47:09","date_gmt":"2024-11-13T06:47:09","guid":{"rendered":"https:\/\/www.keweitrading.com\/?post_type=product&#038;p=5052"},"modified":"2024-11-13T14:47:10","modified_gmt":"2024-11-13T06:47:10","slug":"custom-corten-panels","status":"publish","type":"product","link":"https:\/\/www.keweitrading.com\/fr\/custom-corten-panels\/","title":{"rendered":"Panneaux en corten sur mesure"},"content":{"rendered":"<div data-elementor-type=\"product-post\" data-elementor-id=\"5052\" class=\"elementor elementor-5052\" data-elementor-post-type=\"product\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9805415 e-flex e-con-boxed e-con e-parent\" data-id=\"9805415\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1341fa8 elementor-widget elementor-widget-text-editor\" data-id=\"1341fa8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>T\u00f4le d'acier Corten\/T\u00f4le d'acier r\u00e9sistant aux intemp\u00e9ries<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d787e5 elementor-widget elementor-widget-text-editor\" data-id=\"3d787e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L'acier corten, \u00e9galement connu sous le nom d'acier r\u00e9sistant aux intemp\u00e9ries, est un type d'alliage d'acier qui d\u00e9veloppe une couche de rouille protectrice lorsqu'il est expos\u00e9 aux intemp\u00e9ries. Cette couche de rouille forme une patine stable et protectrice, qui conf\u00e8re aux panneaux corten une r\u00e9sistance accrue \u00e0 la corrosion atmosph\u00e9rique par rapport aux autres aciers.<\/p><p><span style=\"color: var( --e-global-color-primary ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align); background-color: var( --e-global-color-accent ); font-size: 1rem;\">Les panneaux en Corten sont souvent utilis\u00e9s dans les structures ext\u00e9rieures, telles que les fa\u00e7ades de b\u00e2timents, les ponts et les sculptures, en raison de leur aspect distinctif et de leur capacit\u00e9 \u00e0 r\u00e9sister aux conditions climatiques difficiles sans qu'il soit n\u00e9cessaire de les peindre ou de les prot\u00e9ger contre la corrosion. Le nom \"Corten\" est une combinaison des mots \"corrosion\" et \"r\u00e9sistance\".<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d397b0 elementor-widget elementor-widget-image\" data-id=\"2d397b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"330\" src=\"https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/custom-corten-panels-5-1024x423.jpg\" class=\"attachment-large size-large wp-image-5057\" alt=\"custom corten panels\" srcset=\"https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/custom-corten-panels-5-1024x423.jpg 1024w, https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/custom-corten-panels-5-300x124.jpg 300w, https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/custom-corten-panels-5-768x318.jpg 768w, https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/custom-corten-panels-5-18x7.jpg 18w, https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/custom-corten-panels-5-600x248.jpg 600w, https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/custom-corten-panels-5.jpg 1209w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5faa10e elementor-widget elementor-widget-text-editor\" data-id=\"5faa10e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les panneaux corten personnalis\u00e9s de KEWEI pr\u00e9sentent les avantages suivants : excellentes propri\u00e9t\u00e9s m\u00e9caniques, bonne t\u00e9nacit\u00e9, s\u00e9curit\u00e9 d'utilisation, facilit\u00e9 de traitement et de mise en forme, et longue dur\u00e9e de vie.<\/p><p>Convient \u00e0 l'industrie l\u00e9g\u00e8re, \u00e0 la construction navale, \u00e0 la fabrication de pi\u00e8ces structurelles, de pi\u00e8ces m\u00e9caniques, \u00e0 l'ing\u00e9nierie de la construction, \u00e0 l'industrie automobile, aux outils de quincaillerie, etc.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-83c5dbb e-con-full e-flex e-con e-child\" data-id=\"83c5dbb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e063a79 elementor-widget elementor-widget-text-editor\" data-id=\"e063a79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Diff\u00e9rentes tailles<br \/>Surface lisse<br \/>Stabilit\u00e9 chimique<br \/>Une construction facile<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f1cbcb elementor-widget elementor-widget-text-editor\" data-id=\"5f1cbcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ne se corrode pas facilement<br \/>Bonne plasticit\u00e9<br \/>Peut \u00eatre rouill\u00e9 \u00e0 l'avance<br \/>Inspection manuelle<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bb3187 elementor-widget elementor-widget-text-editor\" data-id=\"0bb3187\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Composition chimique (grade Corten A)<\/strong><br \/>Les param\u00e8tres suivants sont ceux du panneau Corten A \u00e0 titre de r\u00e9f\u00e9rence. Pour d'autres qualit\u00e9s de panneaux, veuillez nous contacter pour obtenir une liste de mat\u00e9riaux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cd0a2d elementor-widget elementor-widget-image\" data-id=\"1cd0a2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"606\" height=\"59\" src=\"https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/Chemical-CompositionGrade-Corten-A.jpg\" class=\"attachment-large size-large wp-image-5065\" alt=\"Chemical Composition(Grade Corten A)\" srcset=\"https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/Chemical-CompositionGrade-Corten-A.jpg 606w, https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/Chemical-CompositionGrade-Corten-A-300x29.jpg 300w, https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/Chemical-CompositionGrade-Corten-A-18x2.jpg 18w, https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/Chemical-CompositionGrade-Corten-A-600x58.jpg 600w\" sizes=\"(max-width: 606px) 100vw, 606px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9ee678 elementor-widget elementor-widget-text-editor\" data-id=\"a9ee678\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Propri\u00e9t\u00e9s m\u00e9caniques (grade Corten A)<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a0d765 elementor-widget elementor-widget-image\" data-id=\"5a0d765\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"603\" height=\"57\" src=\"https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/Machanical-PropertiesGrade-Corten-A.jpg\" class=\"attachment-large size-large wp-image-5066\" alt=\"Machanical Properties(Grade Corten A)\" srcset=\"https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/Machanical-PropertiesGrade-Corten-A.jpg 603w, https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/Machanical-PropertiesGrade-Corten-A-300x28.jpg 300w, https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/Machanical-PropertiesGrade-Corten-A-18x2.jpg 18w, https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/Machanical-PropertiesGrade-Corten-A-600x57.jpg 600w\" sizes=\"(max-width: 603px) 100vw, 603px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c867c8d elementor-widget elementor-widget-image\" data-id=\"c867c8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"723\" height=\"617\" src=\"https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/corten-steel-rust-layer-transfromation-diagram.jpg\" class=\"attachment-large size-large wp-image-5067\" alt=\"\" srcset=\"https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/corten-steel-rust-layer-transfromation-diagram.jpg 723w, https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/corten-steel-rust-layer-transfromation-diagram-300x256.jpg 300w, https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/corten-steel-rust-layer-transfromation-diagram-14x12.jpg 14w, https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/corten-steel-rust-layer-transfromation-diagram-600x512.jpg 600w\" sizes=\"(max-width: 723px) 100vw, 723px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bb07a7 elementor-widget elementor-widget-text-editor\" data-id=\"8bb07a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les panneaux Corten pr\u00e9sentent des avantages et des caract\u00e9ristiques uniques qui les rendent largement utilis\u00e9s dans la construction et l'ing\u00e9nierie structurelle :<span style=\"color: var( --e-global-color-primary ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align); background-color: var( --e-global-color-accent ); font-size: 1rem;\">\u00a0<\/span><\/p><p><strong>1. R\u00e9sistance aux intemp\u00e9ries :<\/strong> L'acier Corten pr\u00e9sente une excellente r\u00e9sistance aux intemp\u00e9ries et peut former une couche de rouille uniforme et dense dans l'environnement naturel, offrant ainsi une protection efficace contre la corrosion atmosph\u00e9rique.<\/p><p><strong>2. Aspect unique :<\/strong> La couche de rouille conf\u00e8re \u00e0 l'acier Corten son aspect unique, pr\u00e9sentant une belle couleur naturelle brun-rouge, ce qui en fait un mat\u00e9riau qui attire l'attention dans les domaines de l'architecture et de la sculpture.<\/p><p><strong>3. Pas de peinture :<\/strong> Gr\u00e2ce \u00e0 la bonne protection de la couche de rouille, l'acier Corten ne n\u00e9cessite pas de peinture suppl\u00e9mentaire ou de traitement anticorrosion, ce qui r\u00e9duit les co\u00fbts d'entretien.<\/p><p><strong>4. Solidit\u00e9 et durabilit\u00e9 :<\/strong> L'acier Corten pr\u00e9sente une bonne r\u00e9sistance et une bonne durabilit\u00e9, ce qui le rend appropri\u00e9 pour une vari\u00e9t\u00e9 d'applications structurelles et d'ing\u00e9nierie.<\/p><p><strong>5. Recyclabilit\u00e9 :<\/strong> L'acier Corten est un mat\u00e9riau recyclable, conform\u00e9ment au principe du d\u00e9veloppement durable. Il convient \u00e0 une grande vari\u00e9t\u00e9 d'applications : En raison de ses propri\u00e9t\u00e9s particuli\u00e8res, l'acier Corten est largement utilis\u00e9 dans la construction, les ponts, la sculpture, les navires et d'autres domaines.<\/p><p><strong>6. R\u00e9sistance aux tremblements de terre :<\/strong> La r\u00e9sistance et les performances sismiques de l'acier Corten en font un choix id\u00e9al pour les zones n\u00e9cessitant des exigences d'ing\u00e9nierie particuli\u00e8res.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05641d3 elementor-widget elementor-widget-image\" data-id=\"05641d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"466\" src=\"https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/custom-corten-panels-10-1024x597.jpg\" class=\"attachment-large size-large wp-image-5074\" alt=\"custom corten panels\" srcset=\"https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/custom-corten-panels-10-1024x597.jpg 1024w, https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/custom-corten-panels-10-300x175.jpg 300w, https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/custom-corten-panels-10-768x448.jpg 768w, https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/custom-corten-panels-10-600x350.jpg 600w, https:\/\/www.keweitrading.com\/wp-content\/uploads\/2024\/11\/custom-corten-panels-10.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7985db8 elementor-widget elementor-widget-text-editor\" data-id=\"7985db8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Panneaux Corten pour l'am\u00e9nagement paysager<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfed806 elementor-widget elementor-widget-text-editor\" data-id=\"cfed806\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Quel est le traitement de pr\u00e9-rouille pour l'acier corten ?<\/strong><\/p><p>Il faut beaucoup de temps pour d\u00e9velopper une couche de rouille stable dans la nature. Cela peut grandement affecter l'utilisation de l'acier r\u00e9sistant aux intemp\u00e9ries, en particulier la chute de la rouille liquide et l'envol de la rouille flottante au d\u00e9but de l'utilisation nue.<\/p><p>Le traitement pr\u00e9-rouill\u00e9 peut aider les panneaux en corten \u00e0 s'alt\u00e9rer en peu de temps et la couleur peut \u00e9galement \u00eatre contr\u00f4l\u00e9e.<\/p><p>La finition naturelle de la rouille commence au moment o\u00f9 le produit est cr\u00e9\u00e9 et continuera \u00e0 s'oxyder\/rouiller pour obtenir sa propre finition unique en fonction de son environnement. Au d\u00e9but, la rouille appara\u00eet sous forme de poudre \u00e0 la surface, mais avec le temps, elle p\u00e9n\u00e8tre dans l'acier et \u00e9volue vers une texture dure qui est en fait grav\u00e9e \u00e0 la surface du m\u00e9tal.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Mat\u00e9riau : Acier corten<\/p>\n<p>Type : Bobine d'acier ou panneau d'acier<\/p>\n<p>\u00c9paisseur : 0-60mm Sur mesure<\/p>\n<p>Largeur : 0,6-3000mm sur mesure<\/p>\n<p>Longueur : 2,44-12 m personnalis\u00e9<\/p>\n<p>Service de traitement : Pliage, soudage, d\u00e9coilage, d\u00e9coupage, poin\u00e7onnage<\/p>\n<p><strong>Application :<\/strong><br \/>\nL'acier \u00e0 haute r\u00e9sistance aux intemp\u00e9ries a \u00e9t\u00e9 utilis\u00e9 dans l'ing\u00e9nierie des ponts. Il peut \u00e9galement \u00eatre utilis\u00e9 dans les planchers, les conteneurs, les centrales \u00e9lectriques, etc.<br \/>\nchemin\u00e9es, ing\u00e9nierie ferroviaire et autres aciers d'ext\u00e9rieur, tels que l'acier pour grandes sculptures d'ext\u00e9rieur.<\/p>","protected":false},"featured_media":5056,"template":"","meta":[],"product_brand":[],"product_cat":[54],"product_tag":[],"class_list":["post-5052","product","type-product","status-publish","has-post-thumbnail","product_cat-screen-fence","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.keweitrading.com\/fr\/wp-json\/wp\/v2\/product\/5052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.keweitrading.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.keweitrading.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/www.keweitrading.com\/fr\/wp-json\/wp\/v2\/product\/5052\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.keweitrading.com\/fr\/wp-json\/wp\/v2\/media\/5056"}],"wp:attachment":[{"href":"https:\/\/www.keweitrading.com\/fr\/wp-json\/wp\/v2\/media?parent=5052"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.keweitrading.com\/fr\/wp-json\/wp\/v2\/product_brand?post=5052"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.keweitrading.com\/fr\/wp-json\/wp\/v2\/product_cat?post=5052"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.keweitrading.com\/fr\/wp-json\/wp\/v2\/product_tag?post=5052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}